{"id":3038,"date":"2026-08-06T20:53:45","date_gmt":"2026-08-06T18:53:45","guid":{"rendered":"https:\/\/www.portesetfenetrespresident.com\/portes\/azur\/"},"modified":"2026-08-06T20:53:45","modified_gmt":"2026-08-06T18:53:45","slug":"azur","status":"publish","type":"portes","link":"https:\/\/www.portesetfenetrespresident.com\/en\/doors\/azur\/","title":{"rendered":"Azur"},"content":{"rendered":"<script>function getWR360PopupSkin(){return 'light_clean';}<\/script>","protected":false},"featured_media":3037,"template":"","meta":{"_acf_changed":false},"type-de-porte":[78,75],"class_list":["post-3038","portes","type-portes","status-publish","has-post-thumbnail","type-de-porte-contemporary","type-de-porte-steel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Porte Azur - Portes et fen\u00eatres Pr\u00e9sident<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.portesetfenetrespresident.com\/en\/doors\/azur\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Porte Azur - Portes et fen\u00eatres Pr\u00e9sident\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.portesetfenetrespresident.com\/en\/doors\/azur\/\" \/>\n<meta property=\"og:site_name\" content=\"Portes et fen\u00eatres Pr\u00e9sident\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.portesetfenetrespresident.com\/wp-content\/uploads\/2026\/08\/azur-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.portesetfenetrespresident.com\\\/en\\\/doors\\\/azur\\\/\",\"url\":\"https:\\\/\\\/www.portesetfenetrespresident.com\\\/en\\\/doors\\\/azur\\\/\",\"name\":\"Porte Azur - Portes et fen\u00eatres Pr\u00e9sident\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.portesetfenetrespresident.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.portesetfenetrespresident.com\\\/en\\\/doors\\\/azur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.portesetfenetrespresident.com\\\/en\\\/doors\\\/azur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.portesetfenetrespresident.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/azur-2.png\",\"datePublished\":\"2026-08-06T18:53:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.portesetfenetrespresident.com\\\/en\\\/doors\\\/azur\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.portesetfenetrespresident.com\\\/en\\\/doors\\\/azur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.portesetfenetrespresident.com\\\/en\\\/doors\\\/azur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.portesetfenetrespresident.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/azur-2.png\",\"contentUrl\":\"https:\\\/\\\/www.portesetfenetrespresident.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/azur-2.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.portesetfenetrespresident.com\\\/en\\\/doors\\\/azur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.portesetfenetrespresident.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Azur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.portesetfenetrespresident.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.portesetfenetrespresident.com\\\/en\\\/\",\"name\":\"Portes et fen\u00eatres Pr\u00e9sident\",\"description\":\"La nouvelle g\u00e9n\u00e9ration de portes et fen\u00eatres\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.portesetfenetrespresident.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Porte Azur - Portes et fen\u00eatres Pr\u00e9sident","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.portesetfenetrespresident.com\/en\/doors\/azur\/","og_locale":"en_US","og_type":"article","og_title":"Porte Azur - Portes et fen\u00eatres Pr\u00e9sident","og_url":"https:\/\/www.portesetfenetrespresident.com\/en\/doors\/azur\/","og_site_name":"Portes et fen\u00eatres Pr\u00e9sident","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.portesetfenetrespresident.com\/wp-content\/uploads\/2026\/08\/azur-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.portesetfenetrespresident.com\/en\/doors\/azur\/","url":"https:\/\/www.portesetfenetrespresident.com\/en\/doors\/azur\/","name":"Porte Azur - Portes et fen\u00eatres Pr\u00e9sident","isPartOf":{"@id":"https:\/\/www.portesetfenetrespresident.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.portesetfenetrespresident.com\/en\/doors\/azur\/#primaryimage"},"image":{"@id":"https:\/\/www.portesetfenetrespresident.com\/en\/doors\/azur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.portesetfenetrespresident.com\/wp-content\/uploads\/2026\/08\/azur-2.png","datePublished":"2026-08-06T18:53:45+00:00","breadcrumb":{"@id":"https:\/\/www.portesetfenetrespresident.com\/en\/doors\/azur\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.portesetfenetrespresident.com\/en\/doors\/azur\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.portesetfenetrespresident.com\/en\/doors\/azur\/#primaryimage","url":"https:\/\/www.portesetfenetrespresident.com\/wp-content\/uploads\/2026\/08\/azur-2.png","contentUrl":"https:\/\/www.portesetfenetrespresident.com\/wp-content\/uploads\/2026\/08\/azur-2.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.portesetfenetrespresident.com\/en\/doors\/azur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.portesetfenetrespresident.com\/en\/"},{"@type":"ListItem","position":2,"name":"Azur"}]},{"@type":"WebSite","@id":"https:\/\/www.portesetfenetrespresident.com\/en\/#website","url":"https:\/\/www.portesetfenetrespresident.com\/en\/","name":"Portes et fen\u00eatres Pr\u00e9sident","description":"La nouvelle g\u00e9n\u00e9ration de portes et fen\u00eatres","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.portesetfenetrespresident.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.portesetfenetrespresident.com\/en\/wp-json\/wp\/v2\/portes\/3038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portesetfenetrespresident.com\/en\/wp-json\/wp\/v2\/portes"}],"about":[{"href":"https:\/\/www.portesetfenetrespresident.com\/en\/wp-json\/wp\/v2\/types\/portes"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portesetfenetrespresident.com\/en\/wp-json\/wp\/v2\/media\/3037"}],"wp:attachment":[{"href":"https:\/\/www.portesetfenetrespresident.com\/en\/wp-json\/wp\/v2\/media?parent=3038"}],"wp:term":[{"taxonomy":"type-de-porte","embeddable":true,"href":"https:\/\/www.portesetfenetrespresident.com\/en\/wp-json\/wp\/v2\/type-de-porte?post=3038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}